{"id":286,"count":3,"description":"","link":"https:\/\/amse.it\/en\/precisione\/1-g-en\/","name":"1 g","slug":"1-g-en","taxonomy":"precisione","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/amse.it\/en\/wp-json\/wp\/v2\/precisione\/286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amse.it\/en\/wp-json\/wp\/v2\/precisione"}],"about":[{"href":"https:\/\/amse.it\/en\/wp-json\/wp\/v2\/taxonomies\/precisione"}],"wp:post_type":[{"href":"https:\/\/amse.it\/en\/wp-json\/wp\/v2\/bilance?precisione=286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}